{"id":4109,"date":"2018-01-19T17:07:33","date_gmt":"2018-01-19T19:07:33","guid":{"rendered":"http:\/\/blog.universidades-rusia.com\/br\/?p=4109"},"modified":"2018-01-19T17:07:33","modified_gmt":"2018-01-19T19:07:33","slug":"matilda-um-filme-sobre-nicolas-ii-o-ultimo-czar-russo","status":"publish","type":"post","link":"https:\/\/blog.universidades-rusia.com\/br\/2018\/01\/19\/matilda-um-filme-sobre-nicolas-ii-o-ultimo-czar-russo\/","title":{"rendered":"Matilda: Um filme sobre Nicol\u00e1s II, o \u00faltimo czar russo"},"content":{"rendered":"<p style=\"text-align: justify;\">A vida do \u00faltimo czar russo e sua fam\u00edlia se transformou em uma lenda e faz parte das hist\u00f3rias mais conhecidas da R\u00fassia, especialmente no que diz respeito a sua morte, em Ecaterimburgo, apresentada como um horr\u00edvel massacre que acabou definitivamente com a dinastia dos czares naquele pa\u00eds. No entanto, pouco se fala da vida de Nicolas, antes de se tornar czar, e isso \u00e9 precisamente o que nos revela Matilda.<\/p>\n<p style=\"text-align: justify;\">No artigo anterior intitulado <a href=\"http:\/\/blog.universidades-rusia.com\/br\/2017\/11\/20\/o-misterio-da-gra-duquesa-anastasia-romanov\/\" target=\"_blank\"><strong>O mist\u00e9rio da Gr\u00e3-Duquesa Anastasia Romanov<\/strong><\/a>, contamos um pouco da hist\u00f3ria dessa fam\u00edlia, apesar de forcarmos em Anastasia, mencionamos tamb\u00e9m o fato de toda a fam\u00edlia real ter sido assassinada em Ecaterimburgo, ap\u00f3s serem presos na casa de um comerciante por um longo tempo. O czar Nicol\u00e1s II, sua esposa e seus filhos foram mortos, entre eles o pequeno Aleksei, o herdeiro do trono, terminando assim a dinastia real russa.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2018\/01\/19\/matilda-um-filme-sobre-nicolas-ii-o-ultimo-czar-russo\/#A_controversia_sobre_o_filme\" >A controv\u00e9rsia sobre o filme<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2018\/01\/19\/matilda-um-filme-sobre-nicolas-ii-o-ultimo-czar-russo\/#Mas_por_que_causou_polemica\" >Mas, por que causou pol\u00eamica?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2018\/01\/19\/matilda-um-filme-sobre-nicolas-ii-o-ultimo-czar-russo\/#A_importancia_dos_czares_para_a_Russia\" >A import\u00e2ncia dos czares para a R\u00fassia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2018\/01\/19\/matilda-um-filme-sobre-nicolas-ii-o-ultimo-czar-russo\/#Um_pouco_mais_sobre_a_historia_de_Matilda\" >Um pouco mais sobre a hist\u00f3ria de Matilda<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"A_controversia_sobre_o_filme\"><\/span>A controv\u00e9rsia sobre o filme<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">Essa hist\u00f3ria \u00e9 bem conhecida na R\u00fassia, ela relata o amor do czar Nicol\u00e1s II por uma bailarina de nome Matilda Kshesinskaya, com quem teve uma apaixonada rela\u00e7\u00e3o anos antes de sua coroa\u00e7\u00e3o e seu casamento com Imperatriz Alejandra Fi\u00f3dorovna. O filme conta a hist\u00f3ria de como se conheceram e como o futuro czar ficou cativado pela jovem em um espet\u00e1culo de bal\u00e9 que tinha assistido, no qual ela passa por um pequeno incidente no qual seu seio ficou descoberto. Isso chocou a muitos, pois na cultura russa os czares eram considerados quase sagrados, (no caso do czar Nicol\u00e1s II, de fato \u00e9 um santo canonizado pela igreja ortodoxa) e expor-lhes a cenas de conte\u00fado sexualmente explicito era considerado uma grande falta de respeito.<\/p>\n<p style=\"text-align: justify;\">O cinema russo tem evolu\u00eddo, procurando contar suas pr\u00f3prias hist\u00f3rias e atrair o p\u00fablico acostumado aos tradicionais filmes americanos, no artigo anterior intitulado <a href=\"http:\/\/blog.universidades-rusia.com\/br\/2017\/12\/11\/todo-filme-americano-tem-personagens-russos-por-que\/\" target=\"_blank\"><strong>Todo filme americano tem personagens russos, porque?<\/strong><\/a> Mencionamos um desses filmes que procuram dar um novo olhar para o cinema russo, e que estreou em 2017 como uma vers\u00e3o russa dos Vingadores, o filme \u201cOs guardi\u00f5es\u201d, no qual os russos procuram criar seus pr\u00f3prios her\u00f3is, com figuras alusivas ao seu pa\u00eds como o \u00abhomem-urso\u00bb e outros personagens definitivamente atrelados \u00e0 cultura russa, sem deixar de lado a farta artilharia e a grande quantidade de avi\u00f5es e helic\u00f3pteros que se destacam no filme.<\/p>\n<figure id=\"attachment_4111\" aria-describedby=\"caption-attachment-4111\" style=\"width: 320px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4111 size-full\" src=\"http:\/\/blog.universidades-rusia.com\/br\/wp-content\/uploads\/2018\/01\/matilda20170705095231.jpg\" alt=\"matilda20170705095231\" width=\"320\" height=\"179\" srcset=\"https:\/\/blog.universidades-rusia.com\/br\/wp-content\/uploads\/2018\/01\/matilda20170705095231.jpg 320w, https:\/\/blog.universidades-rusia.com\/br\/wp-content\/uploads\/2018\/01\/matilda20170705095231-300x168.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><figcaption id=\"caption-attachment-4111\" class=\"wp-caption-text\">Cenas de conte\u00fado rom\u00e2ntico entre Nicol\u00e1s e Matilda<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Mas_por_que_causou_polemica\"><\/span>Mas, por que causou pol\u00eamica?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">As raz\u00f5es s\u00e3o variadas, entre elas, as dos ativistas tradicionais da igreja ortodoxa, aos quais o filme pareceu ofensivo ao contar parte da vida do czar, j\u00e1 que ele foi canonizado pela igreja em 2000, por isso, come\u00e7aram a fazer protestos em torno de um filme que nem sequer tinham visto ainda. Todavia, situa\u00e7\u00f5es como esta, em vez de afastar, costumam despertar muito mais a curiosidade do p\u00fablico; dessa forma o filme, durante sua primeira semana em cartaz, superou com folga todas as expectativas em termos de arrecada\u00e7\u00e3o de bilheteria.<\/p>\n<p style=\"text-align: justify;\">A estreia oficial foi realizada no teatro Mariinsky em S\u00e3o Petersburgo, no passado m\u00eas de outubro 2017, apesar de a vida do zar ter terminado em Ecaterimburgo, como mencionamos no artigo intitulado <a href=\"http:\/\/blog.universidades-rusia.com\/br\/2017\/11\/06\/7-segredos-sobre-ecaterimburgo-uma-cidade-para-conhecer-e-amar\/\" target=\"_blank\"><strong>7 segredos sobre Ecaterimburgo, uma cidade para conhecer e amar<\/strong>; <\/a>onde tamb\u00e9m falamos que nessa cidade fica a casa Ipatiev (que pertencia a um comerciante quando ocorreu o massacre dos Romanov) que a partir do ano de 2003 foi transformada em um templo ortodoxo, onde se pode render culto aos chamados \u00abm\u00e1rtires da fam\u00edlia imperial\u00bb.<\/p>\n<figure id=\"attachment_4112\" aria-describedby=\"caption-attachment-4112\" style=\"width: 762px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4112\" src=\"http:\/\/blog.universidades-rusia.com\/br\/wp-content\/uploads\/2018\/01\/1508841026_589605_1508841213_noticia_normal.jpg\" alt=\"1508841026_589605_1508841213_noticia_normal\" width=\"762\" height=\"378\" srcset=\"https:\/\/blog.universidades-rusia.com\/br\/wp-content\/uploads\/2018\/01\/1508841026_589605_1508841213_noticia_normal.jpg 980w, https:\/\/blog.universidades-rusia.com\/br\/wp-content\/uploads\/2018\/01\/1508841026_589605_1508841213_noticia_normal-300x149.jpg 300w, https:\/\/blog.universidades-rusia.com\/br\/wp-content\/uploads\/2018\/01\/1508841026_589605_1508841213_noticia_normal-768x381.jpg 768w\" sizes=\"auto, (max-width: 762px) 100vw, 762px\" \/><figcaption id=\"caption-attachment-4112\" class=\"wp-caption-text\">Premiere do filme no Teatro Mariinski em S\u00e3o Petersburgo<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"A_importancia_dos_czares_para_a_Russia\"><\/span><strong>A import\u00e2ncia dos czares para a R\u00fassia<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">Apesar de o sistema de governo russo ter mudado e j\u00e1 n\u00e3o ser uma monarquia, o povo russo (em particular, os fi\u00e9is ortodoxos) ainda recorda com muito carinhos dos seus czares e a monarquia, que \u00e9 lembrada por eles como uma das melhores \u00e9pocas da R\u00fassia. De fato, no artigo anterior: <a href=\"http:\/\/blog.universidades-rusia.com\/br\/2017\/11\/13\/o-kremlin-de-moscou-a-sede-do-governo-ruso\/\" target=\"_blank\"><strong>O Kremlin em Moscou: sede do governo russo<\/strong><\/a>, vimos como o principal Kremlin do pa\u00eds alberga mem\u00f3rias e coisas alusivas aos czares como o Pal\u00e1cio das Facetas, onde est\u00e3o expostos todos os tronos imperiais e a Catedral da Dormi\u00e7\u00e3o, onde foram coroados todos os czares russos.<\/p>\n<p style=\"text-align: justify;\">Para o povo russo, relembrar os czares e a \u00e9poca \u00e1urea da dinastia \u00e9 bem mais que simplesmente ir a um museu, a uma exposi\u00e7\u00e3o ou ler uma hist\u00f3ria em algum livro sobre o tema; para eles se trata de sua identidade como na\u00e7\u00e3o, das pessoas que os t\u00eam dirigido e os levado a ser o povo que hoje s\u00e3o, amantes da arte, da ci\u00eancia, da tecnologia e inova\u00e7\u00e3o, ou seja, enraizados a sua cultura, mas com o olhar no futuro.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Um_pouco_mais_sobre_a_historia_de_Matilda\"><\/span><strong>Um pouco mais sobre a hist\u00f3ria de Matilda<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">Pode ser que para os russos essa seja uma hist\u00f3ria muito familiar, mas para aqueles que n\u00e3o s\u00e3o desse pa\u00eds, talvez o nome dessa bailarina n\u00e3o seja conhecido, muito menos o seu papel na hist\u00f3ria russa e na vida do czar Nicol\u00e1s II e \u00e9 precisamente esse problema que o filme solucionar. O amor entre esse casal come\u00e7ou no ano de 1890, durante o espet\u00e1culo de bal\u00e9 da formatura de Matilda no Teatro Mariinsky, em S\u00e3o Petersburgo, (mesmo local escolhido para a estreia do filme), onde ela chegou a ser nomeada como a <em>primeira bailarina<\/em>, um t\u00edtulo de honra concedido \u00e0s melhores companhias de bal\u00e9.<\/p>\n<p style=\"text-align: justify;\">Foi uma atra\u00e7\u00e3o m\u00fatua imediata, ela chegou a confessar, e a hist\u00f3ria se passa em um contexto em que a R\u00fassia era um pa\u00eds muito apegado a suas tradi\u00e7\u00f5es e os ortodoxos eram muito obcecados na defesa de seus costumes e tradi\u00e7\u00f5es. Sobre a bailarina polaca Mathilde Kschessinskaya, ou simplesmente, \u201cMatilda\u201d, se conta que esteve envolvida sentimentalmente com outros membros da fam\u00edlia Romanov, como os duques Andr\u00e9i Vlad\u00edmirovich e Serg\u00e9i Mij\u00e1ilovich. No entanto, esses relacionamentos nunca foram comprovados, tampouco foi confirmada a sua rela\u00e7\u00e3o com Nicolas, o que est\u00e1 claro \u00e9 que ambos se conheciam e que sentiam uma forte atra\u00e7\u00e3o m\u00fatua, pois isso \u00e9 atestado em seus escritos.<\/p>\n<p style=\"text-align: justify;\"><strong><em>O que voc\u00ea achou desse tema? Gostaria de ver o filme Matilda, caso fosse exibido em sua cidade?<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Se deseja saber mais sobre como estudar na R\u00fassia, voc\u00ea pode <a href=\"http:\/\/blog.universidades-rusia.com\/br\/reporte-alar\/\" target=\"_blank\"><strong>se inscrever para receber o nosso boletim informativo <\/strong><\/a>e ter acesso totalmente gr\u00e1tis ao artigo intitulado <a href=\"http:\/\/blog.universidades-rusia.com\/br\/reporte-alar\/\" target=\"_blank\"><strong>Como fazer uma gradua\u00e7\u00e3o ou p\u00f3s-gradua\u00e7\u00e3o na R\u00fassia.<\/strong><\/a><\/p>\n<p>Imagem do 0llerbytes Cinema via Flickr.com sob licen\u00e7a creative commons.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A vida do \u00faltimo czar russo e sua fam\u00edlia se transformou em uma lenda e faz parte das hist\u00f3rias mais conhecidas da R\u00fassia, especialmente no que diz respeito a sua morte, em Ecaterimburgo, apresentada como um horr\u00edvel massacre que acabou definitivamente com a dinastia dos czares naquele pa\u00eds. No entanto, pouco se fala da vida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4110,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[1626,1622,1623,1624,1625],"class_list":["post-4109","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-filme-ultimo-czar-russo","tag-matilda-filme","tag-matilda-filme-nicolas-ii","tag-nicolas-ii-czar-russo","tag-nicolas-ii-filme"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/4109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/comments?post=4109"}],"version-history":[{"count":2,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/4109\/revisions"}],"predecessor-version":[{"id":4114,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/4109\/revisions\/4114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/media\/4110"}],"wp:attachment":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/media?parent=4109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/categories?post=4109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/tags?post=4109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}