{"id":4204,"date":"2018-03-02T08:30:53","date_gmt":"2018-03-02T10:30:53","guid":{"rendered":"http:\/\/blog.universidades-rusia.com\/br\/?p=4204"},"modified":"2018-03-02T04:02:28","modified_gmt":"2018-03-02T06:02:28","slug":"os-misterios-do-lago-baikal-na-russia","status":"publish","type":"post","link":"https:\/\/blog.universidades-rusia.com\/br\/2018\/03\/02\/os-misterios-do-lago-baikal-na-russia\/","title":{"rendered":"Os mist\u00e9rios do lago Baikal na R\u00fassia"},"content":{"rendered":"<p style=\"text-align: justify;\">Muito foi dito sobre o famoso Lago Baikal, que est\u00e1 localizado na Sib\u00e9ria, a regi\u00e3o mais fria da R\u00fassia. Este lago \u00e9 famoso por ser o mais extenso e o mais profundo do mundo, suas \u00e1guas s\u00e3o de uma cor azul misteriosa que cativa para possuir e para estranhos, causando tamb\u00e9m que ao seu redor uma grande quantidade de mitos, lendas e supersti\u00e7\u00f5es foram criados.<\/p>\n<p style=\"text-align: justify;\">Os russos s\u00e3o conhecidos precisamente por ser uma cultura cheia de supersti\u00e7\u00f5es, como as mencionadas no artigo anterior intitulado <a href=\"http:\/\/blog.universidades-rusia.com\/br\/2017\/12\/29\/tradicoes-e-supersticoes-russas-o-que-significa-quebrar-um-prato\/\" target=\"_blank\" rel=\"noopener\"><strong>Principais Supersti\u00e7\u00f5es Russas<\/strong><\/a>, destacam algumas dessas tradi\u00e7\u00f5es que tornam a vida dos russos algo cativante, cheio de emo\u00e7\u00e3o, misticismo e at\u00e9 charme, \u00c9 precisamente a f\u00e9 nessas cren\u00e7as que lhes conferem variedade e monotonia fora de suas vidas.<\/p>\n<p style=\"text-align: justify;\">Os mist\u00e9rios que escondem o lago s\u00e3o muitos, mas aqui vamos mencionar apenas os mais conhecidos e tentar aproximar-nos um pouco da realidade por tr\u00e1s do mito, alcan\u00e7ando assim a verdadeira hist\u00f3ria que faz parte da tradi\u00e7\u00e3o russa e que mesmo, porque \u00e9 de um lago t\u00e3o importante, transcende a hist\u00f3ria da humanidade.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2018\/03\/02\/os-misterios-do-lago-baikal-na-russia\/#O_lago_conhecido_mais_antigo_do_mundo\" >O lago conhecido mais antigo do mundo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2018\/03\/02\/os-misterios-do-lago-baikal-na-russia\/#%C2%ABO_olho_azul_da_Siberia%C2%BB\" >\u00abO olho azul da Sib\u00e9ria\u00bb<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2018\/03\/02\/os-misterios-do-lago-baikal-na-russia\/#A_criatura_do_lago\" >A criatura do lago<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2018\/03\/02\/os-misterios-do-lago-baikal-na-russia\/#As_ondas_congeladas\" >As ondas congeladas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2018\/03\/02\/os-misterios-do-lago-baikal-na-russia\/#Avistamentos_de_ovnis\" >Avistamentos de ovnis<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"O_lago_conhecido_mais_antigo_do_mundo\"><\/span>O lago conhecido mais antigo do mundo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">Localizado quase em uma \u00e1rea des\u00e9rtica da Sib\u00e9ria, este \u00e9 um lindo lago, que os habitantes locais costumam chamar de \u00abp\u00e9rola da \u00c1sia\u00bb, especificamente localizado entre o Oblast de Irkust e a Rep\u00fablica da Buryatia, ao sul da Sib\u00e9ria. Estima-se que tem cerca de 25 milh\u00f5es de anos e 1.680 metros de profundidade, o que tamb\u00e9m o torna o lago mais profundo do mundo.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%ABO_olho_azul_da_Siberia%C2%BB\"><\/span>\u00abO olho azul da Sib\u00e9ria\u00bb<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">Os ge\u00f3logos afirmam que este lago foi formado por uma profunda divis\u00e3o entre duas falhas e o movimento tect\u00f4nico da \u00e1rea. Suas \u00e1guas azuis impressionantes ganharam esse apelido, e suas amplas dimens\u00f5es se estendem quase 600 km em toda a R\u00fassia, t\u00e3o grandes que \u00e9 poss\u00edvel v\u00ea-lo a partir do espa\u00e7o exterior. Este lago tem 20% da \u00e1gua doce n\u00e3o congelada do mundo, tamb\u00e9m abriga um grande n\u00famero de esp\u00e9cies, tanto a flora como a fauna, que lhe deram o apelido de \u00abGal\u00e1pagos da R\u00fassia\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00c9 assim que os russos tamb\u00e9m o chamam, (o olho azul da Sib\u00e9ria) porque suas \u00e1guas azuis profundas se destacam em uma \u00e1rea que est\u00e1 permanentemente nevada (Sib\u00e9ria). Nesta regi\u00e3o, h\u00e1 tamb\u00e9m muito a ver, como mencionamos no artigo anterior intitulado <strong><a href=\"http:\/\/blog.universidades-rusia.com\/br\/2017\/12\/25\/curiosidades-da-russia-o-festival-de-grelka-na-siberia\/\" target=\"_blank\" rel=\"noopener\">Curiosidades da R\u00fassia: o festival Grelka na Sib\u00e9ria<\/a><\/strong>, falamos sobre esse festival particular onde as pessoas desafiam o frio, em que \u00e9 a atra\u00e7\u00e3o principal, a competi\u00e7\u00e3o de esqui de biqu\u00edni, onde mais e mais homens e mulheres se juntam a esta competi\u00e7\u00e3o para esquiar com seus melhores mai\u00f4s, como se fosse uma praia.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"A_criatura_do_lago\"><\/span>A criatura do lago<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">A beleza do lago permaneceu aqui, h\u00e1 uma lenda muito popular que fala entre os habitantes da \u00e1rea em que eles falam sobre um drag\u00e3o conhecido como Lusud Khan ou Usan Lobson Khan que vive nas \u00e1guas do lago e h\u00e1 aqueles que afirmam ter visto isso Deitado nas margens do lago, mesmo alguns turistas que o chamam de \u00abpeixe drag\u00e3o\u00bb afirmam ter visto isso em v\u00e1rios tamanhos, ent\u00e3o eles presumem que n\u00e3o \u00e9 uma criatura, mas h\u00e1 dezenas deles.<\/p>\n<p style=\"text-align: justify;\">A lenda se estende por toda a \u00e1rea, mas os petroglifos antigos apareceram nas fal\u00e9sias do Baikal e mostram criaturas muito parecidas com os drag\u00f5es que se diz morar l\u00e1. Eles mostram um monstro de \u00e1gua com grandes garras e de p\u00e9 na margem com um aspecto tem\u00edvel e desafiador. Estes petroglifos sustentam o mito entre os locais e os visitantes.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"As_ondas_congeladas\"><\/span>As ondas congeladas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">Este \u00e9 um fen\u00f4meno que recentemente causou uma reviravolta, especialmente no \u00faltimo inverno, porque um v\u00eddeo foi feito viral em que as ondas s\u00e3o mostradas congelando ao quebrar os bancos. No artigo anterior intitulado <strong><a href=\"http:\/\/blog.universidades-rusia.com\/br\/2018\/01\/05\/as-ondas-congeladas-da-russia-um-espetaculo-da-natureza\/\" target=\"_blank\" rel=\"noopener\">as ondas congeladas da R\u00fassia: um verdadeiro espet\u00e1culo da natureza<\/a><\/strong>, conversamos um pouco sobre esse fen\u00f4meno, o que eles n\u00e3o mencionam no v\u00eddeo e a mensagem que transmitiram \u00e9 que isso acontece precisamente no Lago Baikal, eles apenas mencionam isso \u00c9 um fen\u00f4meno russo, sem especificar o que acontece l\u00e1.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Avistamentos_de_ovnis\"><\/span>Avistamentos de ovnis<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\">Este \u00e9 um fato que atraiu muita aten\u00e7\u00e3o e que n\u00e3o foi confirmado, s\u00e3o simplesmente pescadores da \u00e1rea e outras pessoas que afirmam ter visto grandes luzes entrar e sair do lago em alta velocidade, o que n\u00e3o encontrou uma melhor explica\u00e7\u00e3o do que pensar que era sobre UFOs ou naves espaciais alien\u00edgenas. Eles afirmam que essas s\u00e3o luzes t\u00e3o brilhantes como o sol, no entanto, essas hist\u00f3rias de avistamentos n\u00e3o foram confirmadas por cientistas ou especialistas.<\/p>\n<p style=\"text-align: justify;\">O lago Baikal \u00e9 definitivamente um dos fen\u00f4menos da natureza que tem o planeta Terra e uma das paisagens naturais da R\u00fassia que merecem ser visitadas, como as mencionadas no artigo anterior, intitulado as 10 <a href=\"http:\/\/blog.universidades-rusia.com\/br\/2017\/09\/08\/as-10-paisagens-mais-insolitas-da-russia\/\" target=\"_blank\" rel=\"noopener\"><strong>paisagens naturais mais incomuns da R\u00fassia<\/strong><\/a>, compartilhando o lugar com as minas de diamantes de Mir ou com o lugar mais frio do planeta, Oimiak\u00f3n, no entanto, o Lago Baikal n\u00e3o deixa de ser um dos lugares mais incr\u00edveis que podem ser visitados nesse grande pa\u00eds.<\/p>\n<p style=\"text-align: justify;\"><em><strong>O que voc\u00ea acha sobre este t\u00f3pico? Voc\u00ea gostaria de visitar o m\u00edtico Lago Baikal da R\u00fassia e explorar por si mesmo seus mist\u00e9rios?<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Se voc\u00ea deseja obter mais informa\u00e7\u00f5es sobre estudos na R\u00fassia, pode <strong><a href=\"http:\/\/blog.universidades-rusia.com\/br\/contatos\/\" target=\"_blank\" rel=\"noopener\">contactar-nos<\/a><\/strong> ou escrever sua pergunta na parte inferior (se\u00e7\u00e3o de coment\u00e1rios).<\/p>\n<p>Imagem de 2ilorg via Flickr.com sob a licen\u00e7a creative commons.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Muito foi dito sobre o famoso Lago Baikal, que est\u00e1 localizado na Sib\u00e9ria, a regi\u00e3o mais fria da R\u00fassia. Este lago \u00e9 famoso por ser o mais extenso e o mais profundo do mundo, suas \u00e1guas s\u00e3o de uma cor azul misteriosa que cativa para possuir e para estranhos, causando tamb\u00e9m que ao seu redor [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4205,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/4204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/comments?post=4204"}],"version-history":[{"count":2,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/4204\/revisions"}],"predecessor-version":[{"id":4207,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/4204\/revisions\/4207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/media\/4205"}],"wp:attachment":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/media?parent=4204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/categories?post=4204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/tags?post=4204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}