{"id":4256,"date":"2018-04-02T09:30:58","date_gmt":"2018-04-02T11:30:58","guid":{"rendered":"http:\/\/blog.universidades-rusia.com\/br\/?p=4256"},"modified":"2018-04-02T03:57:26","modified_gmt":"2018-04-02T05:57:26","slug":"tradicoes-russas-celebracao-da-pascoa","status":"publish","type":"post","link":"https:\/\/blog.universidades-rusia.com\/br\/2018\/04\/02\/tradicoes-russas-celebracao-da-pascoa\/","title":{"rendered":"Tradi\u00e7\u00f5es russas: celebra\u00e7\u00e3o da P\u00e1scoa"},"content":{"rendered":"<p style=\"text-align: justify;\">A P\u00e1scoa \u00e9 a principal celebra\u00e7\u00e3o do crist\u00e3o em que a ressurrei\u00e7\u00e3o de Cristo \u00e9 comemorada. Na R\u00fassia, a pacua \u00e9 uma das celebra\u00e7\u00f5es mais importantes junto com o Natal, em um artigo passado chamado <a href=\"http:\/\/blog.universidades-rusia.com\/br\/2017\/10\/13\/as-7-principais-datas-comemorativas-da-russia\/\" target=\"_blank\" rel=\"noopener\"><strong>\u00abAs 7 principais datas comemorativas da R\u00fassia\u00bb<\/strong><\/a>, onde falamos sobre esta celebra\u00e7\u00e3o, desta vez vamos falar sobre isso de uma forma mais detalhada.<\/p>\n<h3 style=\"text-align: justify;\">Data de Celebra\u00e7\u00e3o<\/h3>\n<p style=\"text-align: justify;\">A P\u00e1scoa \u00e9 celebrada no primeiro domingo ap\u00f3s a primeira lua cheia ap\u00f3s o dia do equin\u00f3cio vernal, isto \u00e9, eles s\u00e3o guiados de acordo com o calend\u00e1rio juliano. Na R\u00fassia, geralmente \u00e9 celebrado durante a semana antes da P\u00e1scoa e eles costumam realizar um jejum rigoroso, da mesma forma, eles geralmente realizam prociss\u00f5es acompanhadas de can\u00e7\u00f5es e ora\u00e7\u00f5es e termina quando o padre p\u00e1ra na rua antes de as portas fechadas da igreja, um uma vez que eles abram e anunciam que Cristo ressuscitou. Terminado o ritual, tanto o padre como os fi\u00e9is costumam trocar sauda\u00e7\u00f5es dizendo \u00abCristo ressuscitou\u00bb, durante essas datas \u00e9 muito comum encontrar nos ovos de P\u00e1scoa ou nas ruas da R\u00fassia as seguintes abreviaturas \u00abXB\u00bb que simbolizam \u00ab\u0425\u0440\u0438\u0441\u0442\u043e\u0441 \u0432\u043e\u0441\u043a\u0440\u0435\u0441 \u00ab, que viria dizendo em espanhol\u00bb Cristo ressuscitou \u00ab.<\/p>\n<h3 style=\"text-align: justify;\">Costumes durante a P\u00e1scoa<\/h3>\n<p style=\"text-align: justify;\">Nestas datas t\u00eam diferentes tradi\u00e7\u00f5es, pelo que a parte culin\u00e1ria \u00e9 normalmente destacada, ap\u00f3s uma semana de jejum, pois simboliza a purifica\u00e7\u00e3o e prepara\u00e7\u00e3o da alma para o Domingo de P\u00e1scoa, preparando pratos como: P\u00e1sja, que \u00e9 uma sobremesa \u00e0 base de Queijo e Kulich, que \u00e9 um bolo de vidro e s\u00e3o trazidos ao templo em uma cesta decorada para o efeito, na v\u00e9spera da P\u00e1scoa, para ser aben\u00e7oado pelo padre.<\/p>\n<p style=\"text-align: justify;\">Tamb\u00e9m podemos ver que outros costumes desta data na R\u00fassia, fazem a decora\u00e7\u00e3o de ovos de P\u00e1scoa, que s\u00e3o decorados \u00e0 m\u00e3o, que geralmente s\u00e3o dadas a familiares e amigos. Eles tamb\u00e9m realizam um jogo chamado \u00abegg clinking\u00bb, que consiste em acertar o ovo do oponente com o fim do ovo e o vencedor \u00e9 aquele que consegue manter o ovo quebrado. As crian\u00e7as realizam a busca de ovos na casa como no jardim, no entanto, n\u00e3o h\u00e1 lenda sobre o coelho da P\u00e1scoa.<\/p>\n<p style=\"text-align: justify;\">Durante essas datas, os russos costumam ir visitar o cemit\u00e9rio lembrando os parentes em seus t\u00famulos e l\u00e1 eles comem os ovos de P\u00e1scoa Kulich e Kagor, que \u00e9 um vinho com o qual a Igreja Ortodoxa Russa celebra a Eucaristia e com o que os fi\u00e9is comungam, sendo uma tradi\u00e7\u00e3o herdada da Uni\u00e3o Sovi\u00e9tica at\u00e9 o presente.<\/p>\n<p style=\"text-align: justify;\"><em><strong>O que voc\u00ea acha sobre esse assunto? Voc\u00ea tem alguma tradi\u00e7\u00e3o da P\u00e1scoa que gostaria de compartilhar?<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Se voc\u00ea quiser saber mais sobre estudos na R\u00fassia, <a href=\"http:\/\/blog.universidades-rusia.com\/br\/contatos\/\" target=\"_blank\" rel=\"noopener\"><strong>entre em contato<\/strong><\/a> conosco ou escreva sua pergunta na parte inferior (se\u00e7\u00e3o de coment\u00e1rios).<\/p>\n<p style=\"text-align: justify;\">Imagem do SurFerGiRL30 via Flickr.com sob a licen\u00e7a de creative commons.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A P\u00e1scoa \u00e9 a principal celebra\u00e7\u00e3o do crist\u00e3o em que a ressurrei\u00e7\u00e3o de Cristo \u00e9 comemorada. Na R\u00fassia, a pacua \u00e9 uma das celebra\u00e7\u00f5es mais importantes junto com o Natal, em um artigo passado chamado \u00abAs 7 principais datas comemorativas da R\u00fassia\u00bb, onde falamos sobre esta celebra\u00e7\u00e3o, desta vez vamos falar sobre isso de uma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4257,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[160,1682,1631,1643],"class_list":["post-4256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-cultura-russa","tag-pascoa","tag-russia-celebracoes-culturais","tag-tradicoes-de-russia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/4256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/comments?post=4256"}],"version-history":[{"count":2,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/4256\/revisions"}],"predecessor-version":[{"id":5817,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/4256\/revisions\/5817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/media\/4257"}],"wp:attachment":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/media?parent=4256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/categories?post=4256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/tags?post=4256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}