{"id":5252,"date":"2019-06-24T22:45:35","date_gmt":"2019-06-25T00:45:35","guid":{"rendered":"http:\/\/blog.universidades-rusia.com\/br\/?p=5252"},"modified":"2019-06-24T22:45:40","modified_gmt":"2019-06-25T00:45:40","slug":"saiba-a-quantidade-de-pessoas-que-falam-ingles-na-russia","status":"publish","type":"post","link":"https:\/\/blog.universidades-rusia.com\/br\/2019\/06\/24\/saiba-a-quantidade-de-pessoas-que-falam-ingles-na-russia\/","title":{"rendered":"Saiba a quantidade de pessoas que falam ingl\u00eas na R\u00fassia"},"content":{"rendered":"\n<p>A R\u00fassia \u00e9 o pa\u00eds mais grande do mundo,\ntem uma \u00e1rea de 17,07 milh\u00f5es de quil\u00f4metros quadrados, sua densidade\npopulacional \u00e9 de 8,6 habitantes por km\u00b2, o que indica que sua popula\u00e7\u00e3o \u00e9\nmuito dispersa, a mais dispersa do planeta e al\u00e9m disso \u00e9 uma popula\u00e7\u00e3o\npredominantemente urbana. Ocupa a nona posi\u00e7\u00e3o dos pa\u00edses mais populosos do\nmundo. <\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_79 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2019\/06\/24\/saiba-a-quantidade-de-pessoas-que-falam-ingles-na-russia\/#Seu_idioma\" >Seu idioma<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2019\/06\/24\/saiba-a-quantidade-de-pessoas-que-falam-ingles-na-russia\/#O_ingles_em_terras_russas\" >O ingl\u00eas em terras russas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/blog.universidades-rusia.com\/br\/2019\/06\/24\/saiba-a-quantidade-de-pessoas-que-falam-ingles-na-russia\/#O_ingles_e_a_idade_de_quem_o_fala\" >O ingl\u00eas e a idade de quem o fala<\/a><\/li><\/ul><\/nav><\/div>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Seu_idioma\"><\/span>Seu idioma<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>O russo \u00e9 o idioma oficial deste\npa\u00eds, e 99% da popula\u00e7\u00e3o o entende, cada subdivis\u00e3o nacional russa tem seu\npr\u00f3prio idioma oficial nacional, por isso h\u00e1 mais de 100 l\u00ednguas faladas em\ntoda R\u00fassia, por\u00e9m a maioria dessas l\u00ednguas est\u00e3o em processo de extin\u00e7\u00e3o. Na\nR\u00fassia \u00e9 muito comum que as pessoas estudem e falem outra idioma, com isso surge\na quest\u00e3o de quantas l\u00ednguas s\u00e3o as&nbsp; mais\ninteressantes e mais exigidas pela maioria dos russos. <\/p>\n\n\n\n<p>Depois de uma pesquisa realizada no\nCentro Russo de Pesquisas da Opini\u00e3o P\u00fablica, o resultado foi que o ingl\u00eas \u00e9 o\nidioma mais falado depois do espanhol. \u00c9 bom saber que em geral os russos n\u00e3o\ns\u00f3&nbsp; estudam outra l\u00edngua com fins\nprofissionais, para que possam melhorar as alternativas laborais, estudar em\noutros pa\u00edses, e tamb\u00e9m para que possam se comunicar com os habitantes dos\npa\u00edses vizinhos como Alemanha e Espanha. Isso demonstra um grande interesse dos\nrussos em aprender os idiomas alem\u00e3o, ingl\u00eas e espanhol.&nbsp; <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_ingles_em_terras_russas\"><\/span>O ingl\u00eas em terras russas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A l\u00edngua inglesa&nbsp; tornou-se&nbsp;\na terceira l\u00edngua mais falada depois do mandarim e do espanhol no mundo\npela quantidade de falantes&nbsp; que a t\u00eam\ncomo l\u00edngua materna, cerca de 400 milh\u00f5es de pessoas. E a segunda l\u00edngua a que\nse dedicam a aprender e tamb\u00e9m \u00e9 o idioma oficial ou um dos idiomas oficiais em\nquase 60 estados da Uni\u00e3o Americana. A l\u00edngua inglesa \u00e9 uma l\u00edngua germ\u00e2nica\nocidental, que surgiu nos reinos anglo-sax\u00f5es da Inglaterra.&nbsp;&nbsp; <\/p>\n\n\n\n<p>Devido ao grande poder e influ\u00eancia\nna pol\u00edtica, na economia, na ci\u00eancia, nas for\u00e7as armadas do Reino Unido e da\nGr\u00e3-Bretanha no s\u00e9culo XVIII, o ingl\u00eas espalhou-se de forma ampla pelo mundo\ntodo e mesmo assim \u00e9 o idioma principal do discurso internacional. Tamb\u00e9m\nincluiu-se nos sistemas educativos de muitos pa\u00edses como segunda l\u00edngua e isso\ncom o passar do tempo proporciona um status de superioridade cultural a aqueles\nfalantes n\u00e3o nativos, por isso a causa da influ\u00eancia dos pa\u00edses anglo-sax\u00f5es no\nmundo. <\/p>\n\n\n\n<p>Por ser o terceiro idioma mais falado\nno mundo com cerca de 375 milh\u00f5es de falantes, al\u00e9m dos 508 milh\u00f5es que o tem\ncomo primeira e segunda l\u00edngua, estima-se que o falam mais de 1000 milh\u00f5es no\nmundo. Seu n\u00edvel de dificuldade \u00e9 considerado m\u00e9dio, n\u00e3o \u00e9 dif\u00edcil de aprender\n, possui alguns elementos que complicam um pouco , como acontece na maioria dos\nvocabul\u00e1rios, seus verbos irregulares e a pron\u00fancia.&nbsp; Para poder aprender a l\u00edngua calcula-se que seja\nnecess\u00e1rio umas 200 horas de estudo o que \u00e9 suficiente para subir o primeiro\ndegrau na l\u00edngua. Saber ingl\u00e9s te proporciona boas ofertas de emprego no mundo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"O_ingles_e_a_idade_de_quem_o_fala\"><\/span>O ingl\u00eas e a idade de quem o fala <span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Na R\u00fassia, a maioria da popula\u00e7\u00e3o\nest\u00e1 convencida da necessidade de estudar e aprender uma l\u00edngua estrangeira e o\ningl\u00eas ocupa o primeiro lugar dentro das prefer\u00eancias por ser um idioma\npr\u00e1tico. Em uma pesquisa na qual participaram 1.600 pessoas, um alt\u00edssimo\nporcentagem, 92%, acreditam na necessidade de estudar l\u00ednguas. Nessa mesma\npesquisa o ingl\u00eas foi considerado mais pr\u00e1tico, al\u00e9m disso o ingl\u00eas \u00e9\nobrigat\u00f3rio na faculdade. <\/p>\n\n\n\n<p>No censo realizado em 2010, estima-se\nque 7,5 milh\u00f5es de pessoas falam ingl\u00eas na R\u00fassia, o que representa um 5,48%\ndas pessoas entrevistadas. De tal maneira que o ingl\u00eas e a primeira l\u00edngua\nestrangeira nas escolas russas, no entanto , R\u00fassia ocupa as \u00faltimas posi\u00e7\u00f5es\nna Europa em&nbsp; rela\u00e7\u00e3o ao n\u00edvel de ingl\u00eas\ndos pa\u00edses da Uni\u00e3o Europeia, mas se analisarmos por zonas geogr\u00e1ficas , o\nn\u00edvel mais alto est\u00e1 em Moscou e S\u00e3o Petersburgo. Observa-se tamb\u00e9m que, a\npartir dos 30 anos o n\u00edvel de ingl\u00eas diminui com a idade, significa que o\npessoal jovem fala ingl\u00eas e a medida que a idade aumenta se vai perdendo o\ninteresse pelo idioma.&nbsp;&nbsp; <\/p>\n\n\n\n<p><strong><em>Qual a sua opini\u00e3o sobre esse\nassunto? Voc\u00ea sabia quantas pessoas falam ingl\u00eas na R\u00fassia?<\/em><\/strong><\/p>\n\n\n\n<p>Se voc\u00ea deseja mais informa\u00e7\u00f5es sobre como estudar na R\u00fassia, voc\u00ea pode\u00a0<strong><a href=\"http:\/\/blog.universidades-rusia.com\/br\/reporte-alar\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\">inscrever-se em nossa newsletter<\/a><\/strong> e receber gr\u00e1tis o artigo intitulado sobre como\u00a0<strong><a rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\" href=\"http:\/\/blog.universidades-rusia.com\/br\/reporte-alar\/\" target=\"_blank\">estudar uma gradua\u00e7\u00e3o ou p\u00f3s-gradua\u00e7\u00e3o na R\u00fassia.<\/a><\/strong><\/p>\n\n\n\n<p>Imagen de opsa v\u00eda Pixabay.com bajo\nlicencia creative commons.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A R\u00fassia \u00e9 o pa\u00eds mais grande do mundo, tem uma \u00e1rea de 17,07 milh\u00f5es de quil\u00f4metros quadrados, sua densidade populacional \u00e9 de 8,6 habitantes por km\u00b2, o que indica que sua popula\u00e7\u00e3o \u00e9 muito dispersa, a mais dispersa do planeta e al\u00e9m disso \u00e9 uma popula\u00e7\u00e3o predominantemente urbana. Ocupa a nona posi\u00e7\u00e3o dos pa\u00edses [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[659],"tags":[2177,2174,2175,2173,2176,2178,13],"class_list":["post-5252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-perguntas-frequentes","tag-as-pessoas-falam-ingles-na-russia","tag-descubra-quantas-pessoas-sao-ingles","tag-ingles-na-russia","tag-numero-de-pessoas-fala-ingles-russia","tag-pessoas-inglesas-na-russia","tag-pessoas-que-falam-ingles-na-russia","tag-russia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/5252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/comments?post=5252"}],"version-history":[{"count":1,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/5252\/revisions"}],"predecessor-version":[{"id":5254,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/5252\/revisions\/5254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/media\/5253"}],"wp:attachment":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/media?parent=5252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/categories?post=5252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/tags?post=5252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}