{"id":897,"date":"2014-08-15T18:49:30","date_gmt":"2014-08-15T20:49:30","guid":{"rendered":"http:\/\/blog.universidades-rusia.com\/br\/?p=897"},"modified":"2014-10-06T15:49:53","modified_gmt":"2014-10-06T17:49:53","slug":"alar-outorgou-este-ano-varias-bolsas-de-estudo-100-gratuitas-para-jovens-da-america-latina","status":"publish","type":"post","link":"https:\/\/blog.universidades-rusia.com\/br\/2014\/08\/15\/alar-outorgou-este-ano-varias-bolsas-de-estudo-100-gratuitas-para-jovens-da-america-latina\/","title":{"rendered":"ALAR outorgou este ano v\u00e1rias bolsas de estudo 100% gratuitas  para  jovens da Am\u00e9rica Latina"},"content":{"rendered":"<p style=\"text-align: center;\" align=\"center\"><strong><span style=\"color: #ff0000;\">&#8211; O\u00a0 PROCESSO SELETIVO DE BOLSAS 2014\u00a0 TERMINOU CONVIDAMOS VOC\u00ca A OPTAR POR NOSSO<\/span> <span style=\"color: #ff0000;\">\u00abPROGRAMA DE CUSTOS REDUZIDOS\u00bb VIGENTE<\/span><\/strong><span style=\"color: #ff0000;\"><b>\u00a0<\/b><\/span><span style=\"color: #ff0000;\"><strong><span style=\"color: #ff0000;\"><a href=\"http:\/\/www.universidades-rusia.com\/index.php\/pt\/2013-01-09-19-31-34\/vacantes-en-inscripciones\" target=\"_blank\"><span style=\"color: #0000ff;\">AQU\u00cd<\/span> <\/a>&#8211;\u00a0<\/span><\/strong><\/span><strong><br \/>\n<\/strong><\/p>\n<p>Por ser cada vez maior o interesse em estudar nas universidades na R\u00fassia, e a ALAR\u00a0 por\u00a0 ter conv\u00eanios de coopera\u00e7\u00e3o, administrou 22 bolsas de estudos para gradua\u00e7\u00f5es e mestrados na R\u00fassia, bolsas estas que oferecem o curso, livros e a moradia em alojamentos mobiliados nas resid\u00eancias universit\u00e1rias para cidad\u00e3os da Am\u00e9rica Latina.<\/p>\n<p>As aulas come\u00e7am entre Setembro e Outubro deste ano 2014 ,a sele\u00e7\u00e3o foi feita pela ALAR que recebeu no m\u00eas de Julho a documenta\u00e7\u00e3o dos candidatos.<\/p>\n<p>As universidades que participaram foram as seguintes:<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10151616086704485.1073741833.46338754484&amp;type=3\" target=\"_blank\"><strong><span style=\"color: #000080;\">MGSU \u2013<\/span><\/strong><\/a> Universidade de Constru\u00e7\u00e3o Civil de Moscou : 1vaga<\/p>\n<p><span style=\"color: #000000;\"><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10150827883929485.429049.46338754484&amp;type=3\" target=\"_blank\"><strong><span style=\"color: #0000ff;\">UNN &#8211;<\/span><\/strong><\/a><b>\u00a0<\/b><\/span>Universidade Estatal de Nizhnii N\u00f3vgorod \u201cLobach\u00e9vskii\u201d (Nizhnii N\u00f3vgorod) : 4 vagas<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10151208477879485.475765.46338754484&amp;type=3\" target=\"_blank\"><strong><span style=\"color: #000080;\">SGAU \u2013<\/span><\/strong> <\/a>Universidade Aeroespacial de Samara (Samara) : 14 vagas<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10150206744064485.331076.46338754484&amp;type=3\" target=\"_blank\"><strong><span style=\"color: #0000ff;\">BelGU \u2013<\/span><\/strong><\/a> Universidade Nacional de Investiga\u00e7\u00e3o Estatal de B\u00e9lgorod : 1 vaga<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/media\/set\/?set=a.10150728623199485.422098.46338754484&amp;type=3\" target=\"_blank\"><strong><span style=\"color: #0000ff;\">RUDN \u2013<\/span> <\/strong><\/a>Universidade Russa da Amizade dos Povos : 2 vagas<\/p>\n<p><strong><span style=\"color: #333333;\">O que a bolsa cobre? &#8211;<\/span><\/strong>100% Do custo do curso\u00a0 na Faculdade preparat\u00f3ria de idioma russo e nivelamento acad\u00eamico a gradua\u00e7\u00e3o ou o Mestrado, os livros\u00a0 e a moradia, compartilhada,\u00a0 quarto mobiliado com servi\u00e7os.<\/p>\n<p>Estimativa\u00a0 de gastos para despesas menores\u00a0 entre 900 e 1.600 rublos por m\u00eas, aproximadamente. $ 33 e US $ 56 mensais.<\/p>\n<p><strong><span style=\"color: #333333;\">O que a\u00a0 bolsa n\u00e3o cobre? &#8211;<\/span><\/strong><\/p>\n<p>-Passagens a\u00e9reas a partir do pa\u00eds de origem para a cidade de estudos na R\u00fassia (por conta do\u00a0 aluno) seguro de sa\u00fade\u00a0 US $ 100 a US $ 250 por ano (pago \u00e0 chegada \u00e0 Universidade) -Alimenta\u00e7\u00e3o ,despesas\u00a0 pessoais.<\/p>\n<p>-Despesas: -B\u00e9lgorod, Nizhnii Novgorod, Samara: nada menos do que US $ 250 por m\u00eas, das quais o estudante deve arcar.<\/p>\n<p>-Moscou: Nada menos do que US $ 350 por m\u00eas, das quais o estudante deve arcar.<\/p>\n<p>-Todos Os custos envolvidos na prepara\u00e7\u00e3o de documentos pessoais de acordo com as exig\u00eancias.<\/p>\n<p>-Direito a bolsa de estudos e vaga &#8211; \u00e9 um custo \u00fanico na concess\u00e3o da bolsa de estudos (no final do processo) &#8211; para detalhes, consulte ALAR<\/p>\n<p>-Emiss\u00e3o de visto de estudante no consulado russo.<\/p>\n<p><span style=\"color: #333333;\"><strong>PR\u00c9 &#8211; REQUISITOS Gradua\u00e7\u00e3o :<\/strong><\/span><\/p>\n<p>Ter alcan\u00e7ado 80% na nota escolar em assuntos relacionados \u00e0 carreira escolhida (a exce\u00e7\u00e3o \u00e9 SGAU RUDN que exigem 75%): Para .. Engenharia: 80% em Matem\u00e1tica, F\u00edsica, Qu\u00edmica, Ci\u00eancia da Computa\u00e7\u00e3o ou afins . Para Ci\u00eancias Sociais .. 80% em Hist\u00f3ria, L\u00edngua Espanhola, L\u00edngua Estrangeira, Literatura ou afins Para Medicina e Biol\u00f3gica .. 80% em Biologia, Ci\u00eancias, Qu\u00edmica e Ci\u00eancia da Computa\u00e7\u00e3o ou afins . Demonstrar estudos universit\u00e1rios u outro para neutralizar a falta de pr\u00e9-requisito inicial Limite de idade 26 &#8211; Para Mestrados: Ter conclu\u00eddo a gradua\u00e7\u00e3o obtendo o t\u00edtulo de Bacharel ou licenciatura.<\/p>\n<p>Limite de idade: 35 anos<\/p>\n<p>REQUISITOS<\/p>\n<p>1 Esc\u00e2ner de:\u00a0Passaporte v\u00e1lido at\u00e9 junho de 2016 (apenas a p\u00e1gina com a foto e os detalhes)<\/p>\n<p>2 Certid\u00e3o de Nascimento<\/p>\n<p>3 Atestado M\u00e9dico emitido pela ag\u00eancia de sa\u00fade do Estado com o laudo m\u00e9dico. a. Clinicamente saud\u00e1vel e apto para a faculdade b. Aus\u00eancia de doen\u00e7a HIV e AIDS<\/p>\n<p>4 <strong><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.universidades-rusia.com\/images\/Formul%C3%A1rio_de_Inscri%C3%A7%C3%A3o.pdf\" target=\"_blank\"><span style=\"color: #0000ff;\">Formul\u00e1rio de Inscri\u00e7\u00e3o<\/span><\/a><\/span><\/strong> com foto<\/p>\n<p>5<strong><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.universidades-rusia.com\/images\/Termos_e_Condi%C3%A7%C3%B5es__de_custos_reduzidos_-ALAR_PORTUGU%C3%8AS.pdf\" target=\"_blank\"><span style=\"color: #0000ff;\"> \u00abTermos e Condi\u00e7\u00f5es \u201c<\/span><\/a><\/span>\u00a0<\/strong>assinados<\/p>\n<p>6<strong> Para gradua\u00e7\u00f5es:<\/strong> documentos escolares. Hist\u00f3rico Escolar e certificado de conclus\u00e3o do ensino m\u00e9dio. Para: Mestrados: T\u00edtulo de bacharel ou licenciatura. (materiais, cr\u00e9ditos, horas de estudo e obteve pontua\u00e7\u00e3o)<\/p>\n<p>7 Tradu\u00e7\u00e3o oficial * l\u00edngua russa dos documentos listados acima nos pontos 1, 2, 3 e 6<\/p>\n<p>O tipo Certifica\u00e7\u00e3o depende do pa\u00eds: :: Argentina, Col\u00f4mbia, Costa Rica, Equador, Espanha, Estados Unidos, Honduras, M\u00e9xico, Nicar\u00e1gua, Panam\u00e1, Peru, El Salvador, Uruguai e Venezuela: Depois de serem traduzidos os documentos por um tradutor oficial de l\u00edngua russa, a tradu\u00e7\u00e3o deve ser encadernada. :: Para outros pa\u00edses: Depois de ser traduzido por tradutor oficial, a tradu\u00e7\u00e3o deve ser autenticada pelo c\u00f4nsul da Embaixada da R\u00fassia em seu pa\u00eds 7 A Digitaliza\u00e7\u00e3o do formul\u00e1rios da universidade se entrega quando selecionado. 8 (para quem a bolsa \u00e9 concedida) Apresentar ao Departamento de estrangeiros da universidade , onde iram estudar, o Certificado de Equival\u00eancia (Nostrifikatsia) Documento dos seus estudos no seu pa\u00eds (escola ou universidade) .<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8211; O\u00a0 PROCESSO SELETIVO DE BOLSAS 2014\u00a0 TERMINOU CONVIDAMOS VOC\u00ca A OPTAR POR NOSSO \u00abPROGRAMA DE CUSTOS REDUZIDOS\u00bb VIGENTE\u00a0AQU\u00cd &#8211;\u00a0 Por ser cada vez maior o interesse em estudar nas universidades na R\u00fassia, e a ALAR\u00a0 por\u00a0 ter conv\u00eanios de coopera\u00e7\u00e3o, administrou 22 bolsas de estudos para gradua\u00e7\u00f5es e mestrados na R\u00fassia, bolsas estas que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[168,172],"tags":[243,224,310,180],"class_list":["post-897","post","type-post","status-publish","format-standard","hentry","category-estudos","category-mestrados","tag-bolsa-de-estudos","tag-bolsa-de-estudos-na-russia","tag-intercambio-na-russia","tag-medicina-na-russia"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/comments?post=897"}],"version-history":[{"count":3,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/897\/revisions"}],"predecessor-version":[{"id":969,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/posts\/897\/revisions\/969"}],"wp:attachment":[{"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/media?parent=897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/categories?post=897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.universidades-rusia.com\/br\/wp-json\/wp\/v2\/tags?post=897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}